{"id":1563644,"date":"2025-08-21T15:13:58","date_gmt":"2025-08-21T15:13:58","guid":{"rendered":"https:\/\/tenerifecenter.com\/sale\/affari-con-lo-spazio-callao-salvaje-adeje\/"},"modified":"2025-08-22T11:49:35","modified_gmt":"2025-08-22T11:49:35","slug":"affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr","status":"publish","type":"property_sale","link":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/","title":{"rendered":"Affari con lo spazio Callao Salvaje, Adeje"},"content":{"rendered":"Offriamo in vendita un locale di 160 m2, attualmente affittato a un ristorante. \nSi trova sulla strada principale di Callao Salvaje nella zona commerciale con molte attivit\u00e0: bar, ristoranti, supermercati e altri a pochi metri dal lungomare e dalla spiaggia. Il ristorante non si affaccia direttamente sulla strada principale, ma c&#8217;\u00e8 una pubblicit\u00e0 posizionata con una buona visibilit\u00e0.  All&#8217;interno c&#8217;\u00e8 un bancone bar e 10 tavoli, 15 tavoli possono essere posizionati sulla terrazza. Ottima opportunit\u00e0 per la tua attivit\u00e0, non esitare a contattarci per vivita o maggiori informazioni.\nVYM Canarias, con 15 anni nel mercato e 5 uffici tra Tenerife e Costa Blanca, offre ai suoi clienti una vasta gamma di propriet\u00e0 in vendita e in affitto. Per maggiori informazioni, visita il nostro sito: www.vymcanarias.com . A vostra disposizione: assistenza post vendita, gestione immobiliare, affitti, assistenza assicurativa, allarmi, supporto legale e molto altro.","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-1563644","property_sale","type-property_sale","status-publish","hentry","region_vs-adeje","island_vs-tenerife","city_vs-callao-salvaje","type_vs-affari-con-lo-spazio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania<\/title>\n<meta name=\"description\" content=\"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania\" \/>\n<meta property=\"og:description\" content=\"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/\" \/>\n<meta property=\"og:site_name\" content=\"VYM Canarias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vym.canarias\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T11:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2019\/11\/vym-canarias-icon-512-whitebg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\\\/\",\"url\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\\\/\",\"name\":\"Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/#website\"},\"datePublished\":\"2025-08-21T15:13:58+00:00\",\"dateModified\":\"2025-08-22T11:49:35+00:00\",\"description\":\"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Property for sale\",\"item\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/sale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affari con lo spazio Callao Salvaje, Adeje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/\",\"name\":\"VYM Canarias\",\"description\":\"Real Estate - Tenerife\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania","description":"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/","og_locale":"it_IT","og_type":"article","og_title":"Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania","og_description":"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.","og_url":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/","og_site_name":"VYM Canarias","article_publisher":"https:\/\/www.facebook.com\/vym.canarias","article_modified_time":"2025-08-22T11:49:35+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2019\/11\/vym-canarias-icon-512-whitebg.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/","url":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/","name":"Affari con lo spazio in Vendita a Callao Salvaje, Adeje, Tenerife - Teneryfa, Hiszpania","isPartOf":{"@id":"https:\/\/tenerifecenter.com\/it\/#website"},"datePublished":"2025-08-21T15:13:58+00:00","dateModified":"2025-08-22T11:49:35+00:00","description":"Affari con lo spazio in Vendita: 279000 \u20ac, Superficie totale: 160m2, Soggiorno: 163m2, Camere da letto: 2, Bagni: 2,.","breadcrumb":{"@id":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tenerifecenter.com\/it\/sale\/affari-con-lo-spazio-callao-salvaje-adeje-vs5185vjr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tenerifecenter.com\/it\/"},{"@type":"ListItem","position":2,"name":"Property for sale","item":"https:\/\/tenerifecenter.com\/it\/sale\/"},{"@type":"ListItem","position":3,"name":"Affari con lo spazio Callao Salvaje, Adeje"}]},{"@type":"WebSite","@id":"https:\/\/tenerifecenter.com\/it\/#website","url":"https:\/\/tenerifecenter.com\/it\/","name":"VYM Canarias","description":"Real Estate - Tenerife","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tenerifecenter.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/property_sale\/1563644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/property_sale"}],"about":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/types\/property_sale"}],"author":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/comments?post=1563644"}],"wp:attachment":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/media?parent=1563644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}