{"id":5047,"date":"2019-10-29T21:06:05","date_gmt":"2019-10-29T21:06:05","guid":{"rendered":"https:\/\/tenerifecenter.dev-evocode.net\/?page_id=5047"},"modified":"2023-03-13T17:29:30","modified_gmt":"2023-03-13T17:29:30","slug":"documenti","status":"publish","type":"page","link":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/","title":{"rendered":"Documenti"},"content":{"rendered":"<h2>Procedimento per ottenere il NIE<\/h2>\r\n\r\n<p>Si pu\u00f3 presentare la richiesta per avere il NIE nella sezione \u201c extranjeria \u201c presso il commissariato di polizia\r\n  nel luogo di residenza. Potete presentare la richiesta voi stessi o attraverso una terza persona delegata.\r\n<\/p>\r\n\r\n<h2>Documenti necessari per richiedere il NIE:<\/h2>\r\n\r\n<ul>\r\n  <li> Fotocopia dei documenti di identit\u00e1;<\/li>\r\n  <li> Tassa pagata con timbro della banca;<\/li>\r\n  <li> Se esiste una delega bisogna presentare il certificato corrispondente.<\/li>\r\n<\/ul>\r\n\r\n<p class=\"italic\">*In qualsiasi momento le autorit\u00e1 possono cambiare il procedimento per ottenere il NIE<\/p>\r\n\r\n<h2>APERTURA CONTO CORRENTE<\/h2>\r\n\r\n<ul>\r\n  <li> Passaporto valido;<\/li>\r\n  <li>NIE<\/li>\r\n  <li> Scrittura di compravendita o di riserva dell\u2019immobile per la futura acquisizione<\/li>\r\n  <li> Documento che conferma l\u2019origine del capitale<\/li>\r\n<\/ul>\r\n\r\n<h2>Documenti per la formalizzazione del mutuo<\/h2>\r\n\r\n<ul>\r\n  <li> Dichiarazione dei redditi degli ultimi 2 anni;<\/li>\r\n  <li> Contratto di lavoro ( non inferiore ai 5 anni );<\/li>\r\n  <li> Estratto dei movimenti bancari degli ultimi 12 mesi;<\/li>\r\n  <li> Certificato di propriet\u00e1 senza credito bancario nel paese di residenza;<\/li>\r\n  <li> Certificato di lavoro ( indicando la manzione svolta, il salario, ecc );<\/li>\r\n  <li> Storico creditizio della persona fisica;<\/li>\r\n  <li> In alcuni casi una carta di raccomandazione bancaria;<\/li>\r\n  <li> Altri documenti che confermano l\u2019 esistenza di altre fonti di ingresso economico ( contratti di affitto,\r\n    certificati di dividendi e altra documentazione che si pu\u00f3 richiedere alla banca se il credito chiesto \u00e8 per\r\n    un importo superiore a 500.000 euro ).\r\n  <\/li>\r\n<\/ul>\r\n\r\n<p>\r\n  Tutti i documenti devono essere tradotti in spagnolo e contenere una postilla ( certificazione dei documenti in\r\n  accordo con le norme della Convencion de la Haya del 5 ottobre 1961 ) legalizzata per il Consolato Spagnolo o\r\n  tradotto da un interprete giurato in Spagna ( la forma di certificazione raccomandata dalla nostra compagnia\r\n  ).\r\n<\/p>\r\n\r\n<p>Gli originali dei documenti devono essere portati prima della firma con il notaio per la compravendita di un\r\n  immobile.\r\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Procedimento per ottenere il NIE Si pu\u00f3 presentare la richiesta per avere il NIE nella sezione \u201c extranjeria \u201c presso il commissariato di polizia nel luogo di residenza. Potete presentare la richiesta voi stessi o attraverso una terza persona delegata. Documenti necessari per richiedere il NIE: Fotocopia dei documenti di identit\u00e1; Tassa pagata con timbro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":445600,"parent":3295,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5047","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Documenti per l&#039;acquisto di immobili a Tenerife (Isole Canarie, Spagna)<\/title>\n<meta name=\"description\" content=\"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tenerifecenter.com\/it\/info\/documenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Documenti per l&#039;acquisto di immobili a Tenerife (Isole Canarie, Spagna)\" \/>\n<meta property=\"og:description\" content=\"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tenerifecenter.com\/it\/info\/documenti\/\" \/>\n<meta property=\"og:site_name\" content=\"VYM Canarias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vym.canarias\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T17:29:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2023\/03\/vym-canarias-office-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/\",\"url\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/\",\"name\":\"Documenti per l'acquisto di immobili a Tenerife (Isole Canarie, Spagna)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tenerifecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vym-canarias-office-2.jpeg\",\"datePublished\":\"2019-10-29T21:06:05+00:00\",\"dateModified\":\"2023-03-13T17:29:30+00:00\",\"description\":\"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tenerifecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vym-canarias-office-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/tenerifecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vym-canarias-office-2.jpeg\",\"width\":1920,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/documenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informazione\",\"item\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Documenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/\",\"name\":\"VYM Canarias\",\"description\":\"Real Estate - Tenerife\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tenerifecenter.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Documenti per l'acquisto di immobili a Tenerife (Isole Canarie, Spagna)","description":"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/","og_locale":"it_IT","og_type":"article","og_title":"Documenti per l'acquisto di immobili a Tenerife (Isole Canarie, Spagna)","og_description":"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.","og_url":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/","og_site_name":"VYM Canarias","article_publisher":"https:\/\/www.facebook.com\/vym.canarias","article_modified_time":"2023-03-13T17:29:30+00:00","og_image":[{"width":1920,"height":350,"url":"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2023\/03\/vym-canarias-office-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/","url":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/","name":"Documenti per l'acquisto di immobili a Tenerife (Isole Canarie, Spagna)","isPartOf":{"@id":"https:\/\/tenerifecenter.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/#primaryimage"},"image":{"@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/#primaryimage"},"thumbnailUrl":"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2023\/03\/vym-canarias-office-2.jpeg","datePublished":"2019-10-29T21:06:05+00:00","dateModified":"2023-03-13T17:29:30+00:00","description":"Di quali documenti hai bisogno per acquistare una casa a Tenerife (Isole Canarie)? Una guida dettagliata da VYM Canarias Real Estate Agency.","breadcrumb":{"@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tenerifecenter.com\/it\/info\/documenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/#primaryimage","url":"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2023\/03\/vym-canarias-office-2.jpeg","contentUrl":"https:\/\/tenerifecenter.com\/wp-content\/uploads\/2023\/03\/vym-canarias-office-2.jpeg","width":1920,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/tenerifecenter.com\/it\/info\/documenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tenerifecenter.com\/it\/"},{"@type":"ListItem","position":2,"name":"Informazione","item":"https:\/\/tenerifecenter.com\/it\/info\/"},{"@type":"ListItem","position":3,"name":"Documenti"}]},{"@type":"WebSite","@id":"https:\/\/tenerifecenter.com\/it\/#website","url":"https:\/\/tenerifecenter.com\/it\/","name":"VYM Canarias","description":"Real Estate - Tenerife","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tenerifecenter.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/pages\/5047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/comments?post=5047"}],"version-history":[{"count":0,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/pages\/5047\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/pages\/3295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/media\/445600"}],"wp:attachment":[{"href":"https:\/\/tenerifecenter.com\/it\/wp-json\/wp\/v2\/media?parent=5047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}